{"id":1074,"date":"2020-04-20T20:17:46","date_gmt":"2020-04-20T20:17:46","guid":{"rendered":"https:\/\/encarguelo.com\/blog\/?p=1074"},"modified":"2021-01-22T00:05:42","modified_gmt":"2021-01-22T00:05:42","slug":"cuarentena-activa","status":"publish","type":"post","link":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/","title":{"rendered":"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos hacer en Cuarentena adem\u00e1s de Netflix."},"content":{"rendered":"\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Cinco cosas sencillas pero que te permitir\u00e1n tener una cuarentena m\u00e1s sana y activa. <\/p>\n\n\n\n<!--more-->\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En este momento el mundo vive una Pandemia ocasionada por el virus COVID-19 cuyo origen comenz\u00f3 en Wuhan China. Este virus ya ha quitado la vida de muchas personas a nivel mundial por lo que el mundo entero se puso de acuerdo para permanecer en distanciamiento social. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estar en cuarentena no te permite realizar labores o actividades de una rutina social, por lo que te dejamos 5 actividades que puedes realizar sin moverte de casa y que ayudar\u00e1n a mantener una cuarentena activa y sana.<\/p>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"> 1. Leer.<\/h2>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-02-1024x1024.jpg\" alt=\" en cuarentena libros \" class=\"wp-image-1075\" width=\"291\" height=\"291\" srcset=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-02-1024x1024.jpg 1024w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-02-150x150.jpg 150w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-02-300x300.jpg 300w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-02-768x769.jpg 768w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-02.jpg 1080w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Encuentra un tema que te apasione y busca en internet libros relacionados con esos temas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leer ayuda con el estr\u00e9s, adem\u00e1s de traer consigo una gran cantidad de beneficios educativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No necesitas tener el libro f\u00edsico, hoy en d\u00eda existen muchos art\u00edculos como el <a href=\"https:\/\/encarguelo.com\/amazon-colombia\">Kindle de Amazon<\/a> que te permite descargar libros y leerlos en una tablet virtual. <\/p>\n\n\n\n<div style=\"height:73px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"> 2. Ejercicio.<\/h2>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" src=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-03-1024x1024.jpg\" alt=\"persona haciendo ejercicio en cuarentena\" class=\"wp-image-1076\" width=\"291\" height=\"291\" srcset=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-03-1024x1024.jpg 1024w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-03-150x150.jpg 150w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-03-300x300.jpg 300w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-03-768x769.jpg 768w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-03.jpg 1080w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hay miles de aplicaciones para crear una rutina de ejercicio en casa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es necesario m\u00e1quinas especiales ni entrenadores para realizar 30-40 min de ejercicio diario en casa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A los amantes de las bicicletas o deportistas profesionales del ciclismo pueden <a href=\"https:\/\/encarguelo.com\">comprar un rodillo para bicicleta profesional <\/a>y as\u00ed recorrer kil\u00f3metros dentro de la casa.<\/p>\n\n\n\n<div style=\"height:73px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"> 3. Artes.<\/h2>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img decoding=\"async\" src=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-05-1024x1024.jpg\" alt=\"artes en cuarentena\" class=\"wp-image-1077\" width=\"291\" height=\"291\" srcset=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-05-1024x1024.jpg 1024w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-05-150x150.jpg 150w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-05-300x300.jpg 300w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-05-768x769.jpg 768w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-05.jpg 1080w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Encuentra algo que te apasione en temas art\u00edsticos y convi\u00e9rtelo en un reto para este 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haz dibujos, pinta un cuadro, busca un instrumento musical que te haya llamado la atenci\u00f3n y est\u00fadialo. \u00a1Nunca es tarde!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed te podemos recomendar <a href=\"https:\/\/saposyprincesas.elmundo.es\/consejos\/actualidad\/cosas-utiles-que-hacer-en-cuarentena\/\">10 actividades art\u00edsticas m\u00e1s populares en cuarentena. <\/a><\/p>\n\n\n\n<div style=\"height:73px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"> 4. Cocinar<\/h2>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-04-1024x1024.jpg\" alt=\"cocinar en cuarentena\" class=\"wp-image-1078\" width=\"291\" height=\"291\" srcset=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-04-1024x1024.jpg 1024w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-04-150x150.jpg 150w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-04-300x300.jpg 300w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-04-768x769.jpg 768w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-04.jpg 1080w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nada m\u00e1s rico que comer, imag\u00ednate comer algo bien preparado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toma el tiempo, busca un libro de cocina o compra una freidora de aire, y busca recetas nuevas online.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No te imaginas la cantidad de platos que no pensaste en cocinar y que ahora puedes en tiempos de cuarentena. <\/p>\n\n\n\n<div style=\"height:115px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"> 5. Baila.<\/h2>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-06-1024x1024.jpg\" alt=\"\" class=\"wp-image-1079\" width=\"291\" height=\"291\" srcset=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-06-1024x1024.jpg 1024w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-06-150x150.jpg 150w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-06-300x300.jpg 300w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-06-768x769.jpg 768w, https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-06.jpg 1080w\" sizes=\"(max-width: 291px) 100vw, 291px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Baila con tus seres queridos, hagan una <a href=\"https:\/\/www.sportigo.app\/salud\/bailoterapia-y-sus-beneficios\">bailoterapia<\/a>, busca videos relacionados con coreograf\u00edas y m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bailar ayudar\u00e1 a que tu cuarentena sea menos aburrida y adem\u00e1s puedes aprender algo nuevo que no sab\u00edas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto ayuda a moverte y a hacer ejercicio que es lo m\u00e1s importante en esta cuarentena, mantenerla activa y sana. <\/p>\n\n\n\n<div style=\"height:73px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cinco cosas sencillas pero que te permitir\u00e1n tener una cuarentena m\u00e1s sana y activa.<\/p>\n","protected":false},"author":1,"featured_media":1081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"kk_blocks_editor_width":"","_kiokenblocks_attr":"","_kiokenblocks_dimensions":"","yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"BlogPosting","footnotes":""},"categories":[112],"tags":[72],"class_list":["post-1074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-y-recomendaciones","tag-cuarentena"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":5},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos en Cuarentena.<\/title>\n<meta name=\"description\" content=\"Cuarentena: 5 cosas que puedes realizar en cuarentena para mantenerla lo m\u00e1s activa y sana posible. \u00a1Muy f\u00e1cil! Sin moverte de casa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos en Cuarentena.\" \/>\n<meta property=\"og:description\" content=\"Cuarentena: 5 cosas que puedes realizar en cuarentena para mantenerla lo m\u00e1s activa y sana posible. \u00a1Muy f\u00e1cil! Sin moverte de casa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Encarguelo.com\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-20T20:17:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-22T00:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#\\\/schema\\\/person\\\/167d131d20ee927df26a8c3eee837807\"},\"headline\":\"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos hacer en Cuarentena adem\u00e1s de Netflix.\",\"datePublished\":\"2020-04-20T20:17:46+00:00\",\"dateModified\":\"2021-01-22T00:05:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Sin_ti\u0301tulo-1-01.jpg\",\"keywords\":[\"cuarentena\"],\"articleSection\":[\"TOP y Recomendaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/\",\"url\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/\",\"name\":\"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos en Cuarentena.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Sin_ti\u0301tulo-1-01.jpg\",\"datePublished\":\"2020-04-20T20:17:46+00:00\",\"dateModified\":\"2021-01-22T00:05:42+00:00\",\"description\":\"Cuarentena: 5 cosas que puedes realizar en cuarentena para mantenerla lo m\u00e1s activa y sana posible. \u00a1Muy f\u00e1cil! Sin moverte de casa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Sin_ti\u0301tulo-1-01.jpg\",\"contentUrl\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Sin_ti\u0301tulo-1-01.jpg\",\"width\":1080,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/cuarentena-activa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos hacer en Cuarentena adem\u00e1s de Netflix.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/\",\"name\":\"Blog de Encarguelo.com\",\"description\":\"Conoce los mejores tips y datos sobre las compras en el exterior con env\u00edo a Colombia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#organization\",\"name\":\"encarguelo.com\",\"url\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-1665865845.png\",\"contentUrl\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cropped-1665865845.png\",\"width\":1080,\"height\":324,\"caption\":\"encarguelo.com\"},\"image\":{\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/encarguelo\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@encarguelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/encarguelo.com\\\/blog\\\/#\\\/schema\\\/person\\\/167d131d20ee927df26a8c3eee837807\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd69b1f4962b04b62821f96b0a904cdad2a84b6058368fd05a6f669a2c0faab1?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd69b1f4962b04b62821f96b0a904cdad2a84b6058368fd05a6f669a2c0faab1?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd69b1f4962b04b62821f96b0a904cdad2a84b6058368fd05a6f669a2c0faab1?s=96&d=wavatar&r=g\",\"caption\":\"admin\"}},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos en Cuarentena.","description":"Cuarentena: 5 cosas que puedes realizar en cuarentena para mantenerla lo m\u00e1s activa y sana posible. \u00a1Muy f\u00e1cil! Sin moverte de casa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos en Cuarentena.","og_description":"Cuarentena: 5 cosas que puedes realizar en cuarentena para mantenerla lo m\u00e1s activa y sana posible. \u00a1Muy f\u00e1cil! Sin moverte de casa.","og_url":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/","og_site_name":"Blog de Encarguelo.com","article_published_time":"2020-04-20T20:17:46+00:00","article_modified_time":"2021-01-22T00:05:42+00:00","og_image":[{"width":1080,"height":1081,"url":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-01.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#article","isPartOf":{"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/"},"author":{"name":"admin","@id":"https:\/\/encarguelo.com\/blog\/#\/schema\/person\/167d131d20ee927df26a8c3eee837807"},"headline":"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos hacer en Cuarentena adem\u00e1s de Netflix.","datePublished":"2020-04-20T20:17:46+00:00","dateModified":"2021-01-22T00:05:42+00:00","mainEntityOfPage":{"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/encarguelo.com\/blog\/#organization"},"image":{"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#primaryimage"},"thumbnailUrl":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-01.jpg","keywords":["cuarentena"],"articleSection":["TOP y Recomendaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/","url":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/","name":"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos en Cuarentena.","isPartOf":{"@id":"https:\/\/encarguelo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#primaryimage"},"image":{"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#primaryimage"},"thumbnailUrl":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-01.jpg","datePublished":"2020-04-20T20:17:46+00:00","dateModified":"2021-01-22T00:05:42+00:00","description":"Cuarentena: 5 cosas que puedes realizar en cuarentena para mantenerla lo m\u00e1s activa y sana posible. \u00a1Muy f\u00e1cil! Sin moverte de casa.","breadcrumb":{"@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encarguelo.com\/blog\/cuarentena-activa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#primaryimage","url":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-01.jpg","contentUrl":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2020\/04\/Sin_ti\u0301tulo-1-01.jpg","width":1080,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/encarguelo.com\/blog\/cuarentena-activa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/encarguelo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 hacer en Cuarentena? 5 cosas que recomendamos hacer en Cuarentena adem\u00e1s de Netflix."}]},{"@type":"WebSite","@id":"https:\/\/encarguelo.com\/blog\/#website","url":"https:\/\/encarguelo.com\/blog\/","name":"Blog de Encarguelo.com","description":"Conoce los mejores tips y datos sobre las compras en el exterior con env\u00edo a Colombia.","publisher":{"@id":"https:\/\/encarguelo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encarguelo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/encarguelo.com\/blog\/#organization","name":"encarguelo.com","url":"https:\/\/encarguelo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/encarguelo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-1665865845.png","contentUrl":"https:\/\/encarguelo.com\/blog\/wp-content\/uploads\/2022\/10\/cropped-1665865845.png","width":1080,"height":324,"caption":"encarguelo.com"},"image":{"@id":"https:\/\/encarguelo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/encarguelo\/","https:\/\/www.tiktok.com\/@encarguelo"]},{"@type":"Person","@id":"https:\/\/encarguelo.com\/blog\/#\/schema\/person\/167d131d20ee927df26a8c3eee837807","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bd69b1f4962b04b62821f96b0a904cdad2a84b6058368fd05a6f669a2c0faab1?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bd69b1f4962b04b62821f96b0a904cdad2a84b6058368fd05a6f669a2c0faab1?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bd69b1f4962b04b62821f96b0a904cdad2a84b6058368fd05a6f669a2c0faab1?s=96&d=wavatar&r=g","caption":"admin"}},false]}},"_links":{"self":[{"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/posts\/1074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/comments?post=1074"}],"version-history":[{"count":4,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/posts\/1074\/revisions"}],"predecessor-version":[{"id":1084,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/posts\/1074\/revisions\/1084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/media\/1081"}],"wp:attachment":[{"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/media?parent=1074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/categories?post=1074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/encarguelo.com\/blog\/wp-json\/wp\/v2\/tags?post=1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}